{"id":6750,"date":"2024-10-15T05:00:00","date_gmt":"2024-10-15T09:00:00","guid":{"rendered":"https:\/\/stillcoviding.ca\/fr\/?p=6750"},"modified":"2024-10-20T02:45:42","modified_gmt":"2024-10-20T06:45:42","slug":"changes-in-paxlovid-coverage-raises-concerns-about-affordability-access-in-nb","status":"publish","type":"post","link":"https:\/\/stillcoviding.ca\/fr\/nouvelles\/changes-in-paxlovid-coverage-raises-concerns-about-affordability-access-in-nb\/","title":{"rendered":"Les changements dans la disponibilit\u00e9 de Paxlovid soul\u00e8vent des inqui\u00e9tudes quant \u00e0 l\u2019accessibilit\u00e9 financi\u00e8re et \u00e0 l\u2019acc\u00e8s au N.-B."},"content":{"rendered":"<p>Le Nouveau-Brunswick a pris des mesures pour rendre le Paxlovid plus abordable pour certaines personnes pr\u00e9sentant un risque plus \u00e9lev\u00e9 de tomber gravement malade ou de mourir de la COVID-19, maintenant que le gouvernement f\u00e9d\u00e9ral a cess\u00e9 de fournir gratuitement le m\u00e9dicament antiviral aux provinces. <\/p>\n<p>Mais le m\u00e9dicament con\u00e7u pour r\u00e9duire les sympt\u00f4mes d\u2019une infection et raccourcir la dur\u00e9e de la maladie reste hors de port\u00e9e pour de nombreuses personnes, soit en raison du co\u00fbt d\u2019environ 1&nbsp;400 dollars pour un traitement de cinq jours, soit parce qu\u2019elles n\u2019ont pas acc\u00e8s au m\u00e9dicament en temps voulu, soit parce qu\u2019elles n\u2019ont pas le droit d\u2019en b\u00e9n\u00e9ficier.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le Nouveau-Brunswick a pris des mesures pour rendre le Paxlovid plus abordable pour certaines personnes pr\u00e9sentant un risque plus \u00e9lev\u00e9 de tomber gravement malade ou de mourir de la COVID-19, maintenant que le gouvernement f\u00e9d\u00e9ral a cess\u00e9 de fournir gratuitement le m\u00e9dicament antiviral aux provinces. <\/p>\n<p>Mais le m\u00e9dicament con\u00e7u pour r\u00e9duire les sympt\u00f4mes d\u2019une infection et raccourcir la dur\u00e9e de la maladie reste hors de port\u00e9e pour de nombreuses personnes, soit en raison du co\u00fbt d\u2019environ 1&nbsp;400 dollars pour un traitement de cinq jours, soit parce qu\u2019elles n\u2019ont pas acc\u00e8s au m\u00e9dicament en temps voulu, soit parce qu\u2019elles n\u2019ont pas le droit d\u2019en b\u00e9n\u00e9ficier.<\/p>\n<div class=\"more-link-wrapper\"><a class=\"more-link\" href=\"https:\/\/stillcoviding.ca\/fr\/nouvelles\/changes-in-paxlovid-coverage-raises-concerns-about-affordability-access-in-nb\/\">Lire la suite<span class=\"screen-reader-text\">Les changements dans la disponibilit\u00e9 de Paxlovid soul\u00e8vent des inqui\u00e9tudes quant \u00e0 l\u2019accessibilit\u00e9 financi\u00e8re et \u00e0 l\u2019acc\u00e8s au N.-B.<\/span><\/a><\/div>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[96,16,74,487,12,88],"class_list":["post-6750","post","type-post","status-publish","format-standard","hentry","category-nouvelles","tag-canada","tag-covid-19","tag-nouveau-brunswick","tag-paxlovid","tag-sras-cov-2","tag-traitements-medicaux","entry"],"_links":{"self":[{"href":"https:\/\/stillcoviding.ca\/fr\/wp-json\/wp\/v2\/posts\/6750","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stillcoviding.ca\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/stillcoviding.ca\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/stillcoviding.ca\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/stillcoviding.ca\/fr\/wp-json\/wp\/v2\/comments?post=6750"}],"version-history":[{"count":4,"href":"https:\/\/stillcoviding.ca\/fr\/wp-json\/wp\/v2\/posts\/6750\/revisions"}],"predecessor-version":[{"id":6756,"href":"https:\/\/stillcoviding.ca\/fr\/wp-json\/wp\/v2\/posts\/6750\/revisions\/6756"}],"wp:attachment":[{"href":"https:\/\/stillcoviding.ca\/fr\/wp-json\/wp\/v2\/media?parent=6750"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/stillcoviding.ca\/fr\/wp-json\/wp\/v2\/categories?post=6750"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/stillcoviding.ca\/fr\/wp-json\/wp\/v2\/tags?post=6750"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}