{"id":8453,"date":"2025-05-17T07:00:00","date_gmt":"2025-05-17T11:00:00","guid":{"rendered":"https:\/\/stillcoviding.ca\/fr\/?p=8453"},"modified":"2026-07-01T01:12:52","modified_gmt":"2026-07-01T05:12:52","slug":"fda-approves-novavax-covid-vaccine-with-stricter-new-conditions","status":"publish","type":"post","link":"https:\/\/stillcoviding.ca\/fr\/nouvelles\/fda-approves-novavax-covid-vaccine-with-stricter-new-conditions\/","title":{"rendered":"La FDA approuve le vaccin de Novavax contre la COVID avec de nouvelles conditions plus strictes"},"content":{"rendered":"<p>La Food and Drug Administration (FDA) a approuv\u00e9 vendredi le vaccin de Novavax contre la COVID-19, mais seulement pour les personnes \u00e2g\u00e9es et pour les personnes de plus de 12 ans qui ont au moins une condition m\u00e9dicale qui les met \u00e0 risque \u00e9lev\u00e9 de COVID.<\/p>\n<p>Les conseiller\u00b7\u00e8res scientifiques des Centres pour le contr\u00f4le et la pr\u00e9vention des maladies, qui prennent g\u00e9n\u00e9ralement des d\u00e9cisions sur qui devrait recevoir des injections approuv\u00e9es et quand, ont d\u00e9battu de recommander des injections de COVID uniquement aux Am\u00e9ricain\u00b7e\u00b7s les plus vuln\u00e9rables. La d\u00e9cision de la FDA semblait rendre au moins une partie de leur discussion sans objet.<\/p>\n<p>La nouvelle restriction limitera fortement l\u2019acc\u00e8s au vaccin Novavax pour les personnes de moins de 65 ans en bonne sant\u00e9. Cela pourrait exposer les Am\u00e9ricain\u00b7e\u00b7s qui ne souffrent pas de maladies sous-jacentes \u00e0 un risque si une version plus virulente du coronavirus devait appara\u00eetre. Cela pourrait \u00e9galement limiter les options pour les personnes qui souhaitent se faire vacciner pour un large \u00e9ventail de raisons, notamment pour prot\u00e9ger un proche vuln\u00e9rable.<\/p>\n<p>Le vaccin avait d\u00e9j\u00e0 \u00e9t\u00e9 autoris\u00e9 en cas d\u2019urgence. Les vaccins contre la COVID d\u00e9velopp\u00e9s par Pfizer-BioNTech et Moderna, qui sont plus largement utilis\u00e9s par les Am\u00e9ricain\u00b7e\u00b7s, ont re\u00e7u une approbation compl\u00e8te en 2022. Cependant, les compagnies travaillent sur des vaccins mis \u00e0 jour pour l\u2019automne, et les nouvelles restrictions sur le vaccin de Novavax laissent pr\u00e9sager une approche plus restrictive de la part de la FDA.<\/p>\n<p>Les nouvelles restrictions de la FDA semblent \u00e9galement refl\u00e9ter le degr\u00e9 \u00e9lev\u00e9 de scepticisme \u00e0 l\u2019\u00e9gard des vaccins de Robert F. Kennedy Jr., le secr\u00e9taire \u00e0 la Sant\u00e9, et les autres dirigeant\u00b7e\u00b7s qu\u2019il a nomm\u00e9\u00b7e\u00b7s dans les agences de sant\u00e9.<\/p>\n<p>\u00ab&nbsp;C\u2019est extr\u00eamement d\u00e9cevant&nbsp;\u00bb, a d\u00e9clar\u00e9 la Dre Camille Kotton, m\u00e9decin sp\u00e9cialiste des maladies infectieuses \u00e0 l\u2019h\u00f4pital g\u00e9n\u00e9ral du Massachusetts qui s\u2019occupe de patient\u00b7e\u00b7s immunod\u00e9prim\u00e9\u00b7e\u00b7s et ancienne conseill\u00e8re du CDC.<\/p>\n<p>\u00ab&nbsp;Je ne sais pas pourquoi il\u00b7elles feraient cette restriction; je ne connais aucune indication pour faire ce changement&nbsp;\u00bb, a d\u00e9clar\u00e9 la Dre Kotton, ajoutant que de nombreuses personnes sont encore hospitalis\u00e9es et meurent \u00e0 la suite de la COVID. \u00ab&nbsp;C\u2019est un jour sombre dans la m\u00e9decine am\u00e9ricaine.&nbsp;\u00bb<\/p>\n<p>L\u2019approbation du vaccin, appel\u00e9 Nuvaxovid, exige que la soci\u00e9t\u00e9 effectue des \u00e9tudes pour d\u00e9terminer si le vaccin est associ\u00e9 \u00e0 plusieurs maladies cardiaques. Certaines des recherches requises peuvent \u00eatre compl\u00e9t\u00e9es par les donn\u00e9es disponibles.<\/p>\n<p>Mais une nouvelle \u00e9tude exigerait tr\u00e8s probablement que l\u2019entreprise suive des milliers de personnes en bonne sant\u00e9 \u00e2g\u00e9es de 50 \u00e0 65 ans qui prennent le vaccin ou un placebo. Cette \u00e9tude pourrait co\u00fbter des dizaines de millions de dollars, du moins selon les gens qui connaissent ce travail.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Food and Drug Administration (FDA) a approuv\u00e9 vendredi le vaccin de Novavax contre la COVID-19, mais seulement pour les personnes \u00e2g\u00e9es et pour les personnes de plus de 12 ans qui ont au moins une condition m\u00e9dicale qui les met \u00e0 risque \u00e9lev\u00e9 de COVID.<\/p>\n<p>Les conseiller\u00b7\u00e8res scientifiques des Centres pour le contr\u00f4le et la pr\u00e9vention des maladies, qui prennent g\u00e9n\u00e9ralement des d\u00e9cisions sur qui devrait recevoir des injections approuv\u00e9es et quand, ont d\u00e9battu de recommander des injections de COVID uniquement aux Am\u00e9ricain\u00b7e\u00b7s les plus vuln\u00e9rables. La d\u00e9cision de la FDA semblait rendre au moins une partie de leur discussion sans objet.<\/p>\n<p>La nouvelle restriction limitera fortement l\u2019acc\u00e8s au vaccin Novavax pour les personnes de moins de 65 ans en bonne sant\u00e9. Cela pourrait exposer les Am\u00e9ricain\u00b7e\u00b7s qui ne souffrent pas de maladies sous-jacentes \u00e0 un risque si une version plus virulente du coronavirus devait appara\u00eetre. Cela pourrait \u00e9galement limiter les options pour les personnes qui souhaitent se faire vacciner pour un large \u00e9ventail de raisons, notamment pour prot\u00e9ger un proche vuln\u00e9rable.<\/p>\n<div class=\"more-link-wrapper\"><a class=\"more-link\" href=\"https:\/\/stillcoviding.ca\/fr\/nouvelles\/fda-approves-novavax-covid-vaccine-with-stricter-new-conditions\/\">Lire la suite<span class=\"screen-reader-text\">La FDA approuve le vaccin de Novavax contre la COVID avec de nouvelles conditions plus strictes<\/span><\/a><\/div>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[16,50,256,1472,1471,12,13],"class_list":["post-8453","post","type-post","status-publish","format-standard","hentry","category-nouvelles","tag-covid-19","tag-etats-unis","tag-novavax","tag-nuvaxovid","tag-sanofi","tag-sras-cov-2","tag-vaccins","entry"],"_links":{"self":[{"href":"https:\/\/stillcoviding.ca\/fr\/wp-json\/wp\/v2\/posts\/8453","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stillcoviding.ca\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/stillcoviding.ca\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/stillcoviding.ca\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/stillcoviding.ca\/fr\/wp-json\/wp\/v2\/comments?post=8453"}],"version-history":[{"count":6,"href":"https:\/\/stillcoviding.ca\/fr\/wp-json\/wp\/v2\/posts\/8453\/revisions"}],"predecessor-version":[{"id":8465,"href":"https:\/\/stillcoviding.ca\/fr\/wp-json\/wp\/v2\/posts\/8453\/revisions\/8465"}],"wp:attachment":[{"href":"https:\/\/stillcoviding.ca\/fr\/wp-json\/wp\/v2\/media?parent=8453"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/stillcoviding.ca\/fr\/wp-json\/wp\/v2\/categories?post=8453"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/stillcoviding.ca\/fr\/wp-json\/wp\/v2\/tags?post=8453"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}